{"id":154,"count":2,"description":"","link":"https:\/\/www.futuresteve.com\/index.php\/tags\/sprint\/","name":"sprint","slug":"sprint","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.futuresteve.com\/index.php\/wp-json\/wp\/v2\/tags\/154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.futuresteve.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.futuresteve.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.futuresteve.com\/index.php\/wp-json\/wp\/v2\/posts?tags=154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}